
{"id":39580,"date":"2023-04-02T14:19:09","date_gmt":"2023-04-02T17:19:09","guid":{"rendered":"https:\/\/www.funi.com.ar\/escuela-de-liderazgo\/?post_type=curso&#038;p=39580"},"modified":"2026-03-26T18:48:33","modified_gmt":"2026-03-26T21:48:33","slug":"marca-personal","status":"publish","type":"curso","link":"https:\/\/www.funi.com.ar\/escuela-de-liderazgo\/curso\/marca-personal\/","title":{"rendered":"Marca Personal"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"39580\" class=\"elementor elementor-39580\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e52f6e9 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"e52f6e9\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fa1eeef\" data-id=\"fa1eeef\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1583620a elementor-widget elementor-widget-spacer\" data-id=\"1583620a\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-600c26bf elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"600c26bf\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2b619ac0\" data-id=\"2b619ac0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-375ec1e3 encabezado-curso elementor-widget elementor-widget-text-editor\" data-id=\"375ec1e3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h1 style=\"text-align: center\"><strong>MARCA PERSONAL<\/strong><\/h1><h1 style=\"text-align: center\"><b><span style=\"color: #ffffff\"><em>SOY PROFESIONAL, \u00bfY AHORA QU\u00c9?<\/em><\/span><\/b><\/h1><div>\u00a0<\/div><p style=\"text-align: center\">LOS PRIMEROS PASOS PARA INICIAR TU NEGOCIO PROFESIONAL EXITOSO<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-53388b32 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"53388b32\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4942bb31\" data-id=\"4942bb31\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3bfbca02 elementor-widget elementor-widget-heading\" data-id=\"3bfbca02\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">SOY PROFESIONAL, \u00bfY AHORA QU\u00c9?<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-62a70cc5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"62a70cc5\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3d83287e\" data-id=\"3d83287e\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-73290846 elementor-widget elementor-widget-text-editor\" data-id=\"73290846\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Empieza el desaf\u00edo de salir al mundo a ofertar tus servicios profesionales. En un mercado donde cada vez hay m\u00e1s profesionales y los usuarios son cada vez m\u00e1s exigentes; el saber te\u00f3rico ya no alcanza, porque el saber est\u00e1 a un solo clic.<\/p><p>Las personas a la hora de contratar servicios profesionales esperan m\u00e1s del profesional.<\/p><ul><li>\u00bfC\u00f3mo ser la mejor oferta para que los clientes nos elijan?<\/li><li>\u00bfC\u00f3mo fidelizarlos a los clientes para que nos recomienden y vuelva a contratar?<\/li><li>\u00bfC\u00f3mo ofrecerles una buena propuesta de valor para que quieran pagarnos\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 los honorarios y no nos elijan solo por precio?<\/li><li>\u00bfC\u00f3mo animarnos a salir al mundo laboral a ofrecernos, cuando todav\u00eda nos\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 sentimos inseguros de no saber, o no saber lo suficiente o enfrentarnos al cliente?<\/li><\/ul><p>Estas preguntas, y las que surjan de las inquietudes de los participantes, son las que trabajaremos en este programa.<\/p><p><em><strong>\u00bfEmpezamos el desaf\u00edo?<\/strong><\/em><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-70e8aefc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"70e8aefc\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7e3bbf2e\" data-id=\"7e3bbf2e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-20ac1430 elementor-widget elementor-widget-heading\" data-id=\"20ac1430\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">PROPUESTA DEL TALLER<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2bf88c89 elementor-widget elementor-widget-eael-adv-accordion\" data-id=\"2bf88c89\" data-element_type=\"widget\" data-widget_type=\"eael-adv-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t            <div class=\"eael-adv-accordion\" id=\"eael-adv-accordion-2bf88c89\" data-scroll-on-click=\"no\" data-scroll-speed=\"300\" data-accordion-id=\"2bf88c89\" data-accordion-type=\"toggle\" data-toogle-speed=\"300\">\n            <div class=\"eael-accordion-list\">\n\t\t\t\t\t<div id=\"propuesta\" class=\"elementor-tab-title eael-accordion-header active-default\" tabindex=\"0\" data-tab=\"1\" aria-controls=\"elementor-tab-content-7371\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">PROPUESTA<\/span><\/div><div id=\"elementor-tab-content-7371\" class=\"eael-accordion-content clearfix active-default\" data-tab=\"1\" aria-labelledby=\"propuesta\"><p>A trav\u00e9s de este taller se busca mostrar a los coaches y profesionales independientes los cambios en los consumidores y el mercado, que exigen crear propuestas profesionales diferentes. <br \/>Este proceso puede no ser f\u00e1cil, por eso se requiere partir de la convicci\u00f3n de su importancia y una visi\u00f3n profesional, y personal, muy clara. <br \/>De este modo, el taller resulta te\u00f3rico, pr\u00e1ctico y vivencial; y se focaliza en potenciar los recursos que los profesionales traigan consigo.<\/p><\/div>\n\t\t\t\t\t<\/div><div class=\"eael-accordion-list\">\n\t\t\t\t\t<div id=\"beneficios-de-participar-en-el-taller\" class=\"elementor-tab-title eael-accordion-header active-default\" tabindex=\"0\" data-tab=\"2\" aria-controls=\"elementor-tab-content-7372\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">BENEFICIOS DE PARTICIPAR EN EL TALLER<\/span><\/div><div id=\"elementor-tab-content-7372\" class=\"eael-accordion-content clearfix active-default\" data-tab=\"2\" aria-labelledby=\"beneficios-de-participar-en-el-taller\"><p>Se espera que los participantes logren:<\/p><ul><li>Apropiarse de la realidad del mercado actual y de la psicolog\u00eda de los consumidores actuales.<\/li><li>Creaci\u00f3n de una visi\u00f3n profesional, y personal.<\/li><li>Autoconciencia y autoconocimiento de los recursos individuales.<\/li><li>Desarrollar una propuesta profesional en base al sistema de las 4Q.<\/li><\/ul><\/div>\n\t\t\t\t\t<\/div><div class=\"eael-accordion-list\">\n\t\t\t\t\t<div id=\"modalidad\" class=\"elementor-tab-title eael-accordion-header active-default\" tabindex=\"0\" data-tab=\"3\" aria-controls=\"elementor-tab-content-7373\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">MODALIDAD<\/span><\/div><div id=\"elementor-tab-content-7373\" class=\"eael-accordion-content clearfix active-default\" data-tab=\"3\" aria-labelledby=\"modalidad\"><p>ONLINE, 100%. 6 clases en vivo de 2 horas cada una.<\/p><\/div>\n\t\t\t\t\t<\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-12dc1a9e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"12dc1a9e\" data-element_type=\"section\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-525c821c\" data-id=\"525c821c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-64697d73 elementor-widget elementor-widget-heading\" data-id=\"64697d73\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">DIRIGIDO A<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-37730a41 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"37730a41\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-2e504d7d\" data-id=\"2e504d7d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-71d8cc37 elementor-align-left elementor-widget__width-auto elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"71d8cc37\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-dot-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Coaches Profesionales.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-dot-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Estudiantes de Coaching y\/o carreras afines.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-dot-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Profesionales independientes (Abogado, Psic\u00f3logo, Contador, Arquitectos, etc).<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-dot-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Estudiantes para carreras profesionales.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-dot-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Exalumnos y alumnos de todos los cursos y carreras en FUNI (Productor de seguros, Mandatarios del automotor, Martillero P\u00fablico, Despachante de aduana, Consultores, etc).<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-dot-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Toda aquella persona que necesite visibilizar su profesi\u00f3n para tener ingresos propios.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2f8f81f3 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"2f8f81f3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6e415c4f\" data-id=\"6e415c4f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-527d5325 elementor-widget elementor-widget-heading\" data-id=\"527d5325\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">REQUISITOS PARA LA OBTENCI\u00d3N DEL CERTIFICADO<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a95c70a elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"7a95c70a\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">80 % de asistencia.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Todas las cuotas pagas.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Participaci\u00f3n activa durante las reuniones.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Completar las \u201ctareas\u201d propuestas.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1725aa12 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"1725aa12\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-66911411 elementor-widget elementor-widget-heading\" data-id=\"66911411\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">PROGRAMA<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5105642d elementor-view-framed elementor-shape-circle elementor-position-top elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"5105642d\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/www.funi.com.ar\/wp-content\/uploads\/2023\/05\/Programa-MARCA-PERSONAL-1-2023-web.pdf\" target=\"_blank\" class=\"elementor-icon elementor-animation-\" tabindex=\"-1\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-file-pdf\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.funi.com.ar\/wp-content\/uploads\/2023\/05\/Programa-MARCA-PERSONAL-1-2023-web.pdf\" target=\"_blank\" >\n\t\t\t\t\t\t\tPrograma del taller.\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-544d21c3 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"544d21c3\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b145095 elementor-widget elementor-widget-heading\" data-id=\"6b145095\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">DURACI\u00d3N<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6167f612 elementor-widget elementor-widget-text-editor\" data-id=\"6167f612\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"text-align: center\">3 MESES. Lunes de 14.30 a 16.30 hs. (Hora Argentina).<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-11d3a6f6 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"11d3a6f6\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-35662415 elementor-widget elementor-widget-heading\" data-id=\"35662415\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">CURSADA<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-173a0c9f elementor-widget elementor-widget-text-editor\" data-id=\"173a0c9f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"text-align: center\"><span style=\"text-decoration: underline\">DIAS DE CURSADA<\/span><br \/>JUNIO: 12, 26<br \/>JULIO 10,24<br \/>AGOSTO: 7, 28<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-320202cc\" data-id=\"320202cc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8a02392 eael-infobox-content-align--center elementor-widget elementor-widget-eael-info-box\" data-id=\"8a02392\" data-element_type=\"widget\" data-widget_type=\"eael-info-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t        <div class=\"eael-infobox icon-on-top\">\n\t            <div class=\"infobox-content\">\n        <div><h4 style=\"text-align: center\">Taller de Marca Personal<\/h4><\/div>        <\/div>\n            <\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-683d07a elementor-widget elementor-widget-eael-creative-button\" data-id=\"683d07a\" data-element_type=\"widget\" data-widget_type=\"eael-creative-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t        <div class=\"eael-creative-button-wrapper\">\n\n            <a class=\"eael-creative-button eael-creative-button--default eael-cb-icon-position-left\" href=\"https:\/\/wa.me\/5491162712547?text=ELPERSONAL%20-%20Quiero%20m%C3%A1s%20informaci%C3%B3n\" data-text=\"\">\n            \t    \n                <div class=\"creative-button-inner\">\n\n                                            <span class=\"eael-creative-button-icon-left\"><i aria-hidden=\"true\" class=\"fab fa-whatsapp\"><\/i><\/span>                    \n                    <span class=\"cretive-button-text\">Ingresa aqu\u00ed para recibir mas informaci\u00f3n por WhatsApp<\/span>\n\n                                    <\/div>\n\t                        <\/a>\n        <\/div>\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a44c88f elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"3a44c88f\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-inner-section elementor-element elementor-element-19af1ee5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"19af1ee5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-5c4285d3\" data-id=\"5c4285d3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5c62146d elementor-position-left elementor-vertical-align-middle elementor-widget__width-auto elementor-view-default elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"5c62146d\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-certificate\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tTodas nuestras carreras y cursos tienen certificaciones y t\u00edtulos oficiales. \t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-746659e9 elementor-position-left elementor-vertical-align-middle elementor-widget__width-auto elementor-view-default elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"746659e9\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-graduation-cap\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tNuestros cursos son dictados por profesionales expertos en cada materia.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-inner-section elementor-element elementor-element-50c9a80d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"50c9a80d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-bf1f1e8\" data-id=\"bf1f1e8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5302149 elementor-widget elementor-widget-image\" data-id=\"5302149\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"575\" height=\"40\" src=\"https:\/\/www.funi.com.ar\/escuela-de-liderazgo\/wp-content\/uploads\/sites\/12\/2023\/03\/575X40-medios-pago.jpg\" class=\"attachment-large size-large wp-image-39509\" alt=\"\" srcset=\"https:\/\/www.funi.com.ar\/escuela-de-liderazgo\/wp-content\/uploads\/sites\/12\/2023\/03\/575X40-medios-pago.jpg 575w, https:\/\/www.funi.com.ar\/escuela-de-liderazgo\/wp-content\/uploads\/sites\/12\/2023\/03\/575X40-medios-pago-300x21.jpg 300w\" sizes=\"(max-width: 575px) 100vw, 575px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6485032b elementor-section-full_width elementor-section-content-middle elementor-section-height-default elementor-section-height-default\" data-id=\"6485032b\" data-element_type=\"section\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2123a53\" data-id=\"2123a53\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-23519abe elementor-widget elementor-widget-heading\" data-id=\"23519abe\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">METODOLOG\u00cdA DE ABORDAJE\n<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ed818ee elementor-widget elementor-widget-text-editor\" data-id=\"ed818ee\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"text-align: left\">Se trabajar\u00e1 en forma sincr\u00f3nica (clases online en vivo) y con \u201ctareas\u201d entre clases para reforzar el proceso de aprendizaje y transformaci\u00f3n. El esquema de contenidos est\u00e1 dise\u00f1ado y estructurado para ser abordado en su totalidad en las horas del curso, sin embargo, durante las clases se priorizar\u00e1 el aprendizaje pr\u00e1ctico y vivencial, y la satisfacci\u00f3n de las inquietudes de los participantes.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-734a1317 elementor-section-full_width elementor-section-content-middle elementor-section-height-default elementor-section-height-default\" data-id=\"734a1317\" data-element_type=\"section\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-13115b76\" data-id=\"13115b76\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-716571e7 elementor-widget elementor-widget-heading\" data-id=\"716571e7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">ARANCEL<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-721843ca elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"721843ca\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7a51d1ee\" data-id=\"7a51d1ee\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6ef45ecb elementor-widget elementor-widget-text-editor\" data-id=\"6ef45ecb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul><li><strong>Valor para residentes ARGENTINOS<\/strong>:<\/li><\/ul><p style=\"padding-left: 80px\">Alumnos o exaulmnos de FUNI. Inscripci\u00f3n 50 % Off.<br \/>Consultar por descuentos especiales para grupos.<br \/>Consultar por beneficios en la inscripci\u00f3n temprana.<\/p><p style=\"padding-left: 80px\">Forma de Pago: Transferencia Bancaria, Tarjeta de d\u00e9bito, Tarjeta de Cr\u00e9dito, Dinero en MercadoPago, efectivo.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-18a5d08\" data-id=\"18a5d08\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6a255bdf elementor-widget elementor-widget-text-editor\" data-id=\"6a255bdf\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul><li><strong>Valor para EXRANJEROS:<\/strong><\/li><\/ul><p style=\"padding-left: 80px\">Alumnos o exaulmnos de FUNI. Inscripci\u00f3n 50 % Off.<br \/>Consultar por descuentos especiales para grupos.<br \/>Consultar por beneficios en la inscripci\u00f3n temprana.<br \/><br \/><\/p><p style=\"padding-left: 80px\">Forma de Pago: Paypal<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4466b933 elementor-section-full_width elementor-section-content-middle elementor-section-height-default elementor-section-height-default\" data-id=\"4466b933\" data-element_type=\"section\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-59e2bb0f\" data-id=\"59e2bb0f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-54855388 elementor-widget elementor-widget-heading\" data-id=\"54855388\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">SER PARTE DE NUESTRA COMUNIDAD<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1bf4be3b elementor-widget elementor-widget-text-editor\" data-id=\"1bf4be3b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>En la Escuela de Liderazgo FUNI estamos al servicio de la mejora continua del ser humano (en tanto ser social) consideramos que la interacci\u00f3n es un valor diferencial.<br \/>Creemos en el sentido de pertenencia, en formar equipos de aprendientes y generar relaciones sostenibles, duraderas para que el logro de la certificaci\u00f3n sea co-creado en comunidad, respetando los tiempos de aprendizaje personal y colectivo.<\/p><p>Durante tu paso de formaci\u00f3n con nosotros, en cada clase y fuera de ella, buscamos la interacci\u00f3n permanente, crear comunidad con el fin de ser colaborativos, formar conceptos juntos y bajarlos a tu realidad circunstancial.<\/p><p>Valoramos las relaciones y por eso sentir\u00e1s que estamos recorriendo juntos tu aprendizaje personal y profesional.<\/p><p>Nos interesa que este nuevo camino, sea el mejor recorrido que hayas logrado hasta ahora en tu vida.<\/p><p>Te invitamos a transitar juntos este espacio que sin dudas creceremos en comunidad.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4a7d1538 elementor-section-full_width elementor-section-content-middle elementor-section-height-default elementor-section-height-default\" data-id=\"4a7d1538\" data-element_type=\"section\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-35ebd5d4\" data-id=\"35ebd5d4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6cbdffbc elementor-widget elementor-widget-heading\" data-id=\"6cbdffbc\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">TESTIMONIOS<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d80d76a elementor-widget elementor-widget-lae-carousel\" data-id=\"5d80d76a\" data-element_type=\"widget\" data-widget_type=\"lae-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\n    <div id=\"lae-carousel-5d80d76a\"\n                                      class=\"lae-carousel lae-container\"\n                                      data-settings='{&quot;arrows&quot;:true,&quot;dots&quot;:false,&quot;autoplay&quot;:true,&quot;autoplay_speed&quot;:3000,&quot;animation_speed&quot;:300,&quot;pause_on_hover&quot;:true,&quot;display_columns&quot;:1,&quot;scroll_columns&quot;:1,&quot;gutter&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;12&quot;,&quot;sizes&quot;:[]},&quot;tablet_width&quot;:800,&quot;tablet_display_columns&quot;:1,&quot;tablet_scroll_columns&quot;:1,&quot;mobile_width&quot;:480,&quot;mobile_display_columns&quot;:1,&quot;mobile_scroll_columns&quot;:1}'>\n\n        \n            \n            \n<div class=\"lae-carousel-item\">\n\n    <h4 style=\"text-align: center\">Iris Roumec. Bio.Coach.<\/h4><p>En el curso&#8230; me di cuenta de lo poco que sab\u00eda sobre el mundo profesional del coaching, para m\u00ed era recibirse y tener clientes jajaja nada m\u00e1s lejos de la realidad, hay un proceso maravilloso detr\u00e1s y lo descubr\u00ed gracias a Euge que es una genia, no solo brind\u00e1ndonos teor\u00eda muy sencilla de aplicar sino tambi\u00e9n por su invaluable mentor\u00eda, que me ayud\u00f3 a superar mis l\u00edmites y \u00abvenderme a mi misma\u00bb.C\u00f3mo resultado\u2026 a pocas semanas de comenzar el curso ya hab\u00eda creado mi marca personal, encontr\u00e9 mi voz, mi imagen, mi propuesta de valor y despu\u00e9s vino mi primer cliente! \u00a1Qu\u00e9 emoci\u00f3n ver c\u00f3mo t\u00fa trabajo da frutos! Hoy veo mis reels e historias con m\u00e1s de 3 mil vistas y eso para m\u00ed es much\u00edsimo! As\u00ed que los animo a iniciar este hermoso recorrido, consulten todo lo que no entiendan, compartan en los grupos porque eso hace mucho m\u00e1s enriquecedor el proceso y a disfrutar de los resultados!!!<\/p>\n<\/div><!-- .lae-carousel-item -->\n        \n            \n            \n<div class=\"lae-carousel-item\">\n\n    <h4 style=\"text-align: center\">Laura Nicce-Coach Ontol\u00f3gica profesional ACTP-ICF.<\/h4><p style=\"text-align: left\">Gracias Euge! Me brindaste otra mirada hacia un mundo que cre\u00eda conocido y hoy percibo e interact\u00fao desde otro lugar. Pas\u00e9 de usar las redes como eventualmente informativas a conocer todos los formatos con los que pod\u00eda crear contenido, darle sentido identidad, estructura y a la vez flexibilidad, herramientas, conceptos y tecnicismos, pude darle sentido y un marco profesional. Excelente mi experiencia y me llev\u00e9 aprendizaje para potenciarme infinitamente. Y destacar tu accesibilidad, gu\u00eda, experiencia, calidez y disponibilidad. Gracias!<\/p>\n<\/div><!-- .lae-carousel-item -->\n        \n            \n            \n<div class=\"lae-carousel-item\">\n\n    <h4 style=\"text-align: center\">Flavia Parma.<\/h4><p>No ten\u00eda idea de c\u00f3mo ordenar todo lo que aprend\u00ed en la carrera y con todas las herramientas que tengo y esto me hizo ver la posibilidad de tener mi propia consultora de servicios, la puedo ver, veo los detalles .. antes de este curso eran todas herramientas acumuladas , como un placer mal ordenado. Estoy feliz.<\/p>\n<\/div><!-- .lae-carousel-item -->\n        \n            \n            \n<div class=\"lae-carousel-item\">\n\n    <h4 style=\"text-align: center\">Noha-Coach Ontol\u00f3gica.<\/h4><p>A m\u00ed el taller me s\u00faper sirvi\u00f3, consegu\u00ed clientas que me contactaron por las RRSS, me sent\u00ed acompa\u00f1ada en todo momento en el grupo, y en confianza de compartir mis publicaciones y cosas que me pasaban para que entre todas nos di\u00e9ramos apoyo, eso es muy muy muy importante para m\u00ed, el no sentirse sola al arrancar.<\/p>\n<\/div><!-- .lae-carousel-item -->\n        \n    <\/div><!-- .lae-carousel -->\n\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3bf5a869 elementor-section-full_width elementor-section-content-middle elementor-section-height-default elementor-section-height-default\" data-id=\"3bf5a869\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2b70e804\" data-id=\"2b70e804\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e3903a9 elementor-widget elementor-widget-text-editor\" data-id=\"e3903a9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h5><strong>Coordinador<\/strong><\/h5><p>Mat\u00edas Sebasti\u00e1n de la Fuente \u2013 PCC \u2013 ICF<br \/>Cel. directo: +54 911 5701 7959<br \/><a href=\"https:\/\/web.whatsapp.com\/send?phone=5491152461863\">WhatsApp Comercial Funi: +5491152461863<\/a><br \/><a href=\"mailto:matiasdelafuente@funicomapu.com.ar\">matiasdelafuente@funicomapu.com.ar<\/a><br \/>www.funi.com.ar<\/p><h6><strong><img decoding=\"async\" class=\"alignnone wp-image-39307\" src=\"https:\/\/webdesa.funi.com.ar\/escuela-de-coaching\/wp-content\/uploads\/sites\/12\/2021\/10\/0-PCC-300x300.png\" alt=\"\" width=\"69\" height=\"69\" srcset=\"https:\/\/www.funi.com.ar\/escuela-de-liderazgo\/wp-content\/uploads\/sites\/12\/2021\/10\/0-PCC-300x300.png 300w, https:\/\/www.funi.com.ar\/escuela-de-liderazgo\/wp-content\/uploads\/sites\/12\/2021\/10\/0-PCC-150x150.png 150w, https:\/\/www.funi.com.ar\/escuela-de-liderazgo\/wp-content\/uploads\/sites\/12\/2021\/10\/0-PCC.png 340w\" sizes=\"(max-width: 69px) 100vw, 69px\" \/><\/strong><strong><img decoding=\"async\" class=\"alignnone wp-image-39425\" src=\"https:\/\/webdesa.funi.com.ar\/escuela-de-coaching\/wp-content\/uploads\/sites\/12\/2023\/03\/LOGO-COP-300x123.jpg\" alt=\"\" width=\"158\" height=\"65\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-39427\" src=\"https:\/\/webdesa.funi.com.ar\/escuela-de-coaching\/wp-content\/uploads\/sites\/12\/2023\/03\/LOGO-FICOP-300x107.png\" alt=\"\" width=\"163\" height=\"58\" \/><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-39426 alignnone\" src=\"https:\/\/webdesa.funi.com.ar\/escuela-de-coaching\/wp-content\/uploads\/sites\/12\/2023\/03\/LOGO-CSM-300x300.png\" alt=\"\" width=\"71\" height=\"71\" \/><\/strong><\/h6><p>Coach Ontol\u00f3gico Profesional PCC &#8211; ICF. Certificaci\u00f3n Internacional de Coaching de Equipos. Master Coach Ontol\u00f3gico Profesional. T\u00e9cnico Superior en Administraci\u00f3n de Empresas.<br \/><a href=\"http:\/\/www.funi.com.ar\">Coordinador de la Escuela de Liderazgo<\/a> \u2013 FUNI. Director e Instructor de la Carrera de Coaching Ontol\u00f3gico Profesional \u2013 ACTP &#8211; ICF. Mentoring para exalumnos y Coaching de Equipos \u00c1giles.<br \/>Scrum Master \u2013 Scrum Alliance. Neurosicoeducador.<br \/>Coach COPA y Miembro de AACOP &#8211; Asociaci\u00f3n Argentina de Coaching Profesional y Coach COA de FICOP -Federaci\u00f3n Internacional de Coaching Profesional. Miembro de la ICF \u2013 International Coach Federation.<br \/>Consultor Organizacional independiente y consultoras varias.<br \/><a href=\"http:\/\/www.matiasdelafuente.com\">www.matiasdelafuente.com<\/a><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-98be75d elementor-widget elementor-widget-text-editor\" data-id=\"98be75d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h5><strong>Instructora del programa:<\/strong><\/h5><p><b>Mar\u00eda Eugenia Queh\u00e9<\/b><br \/>Coach, entrenadora y mentora de Abogados en Dise\u00f1o Profesional e Inteligencia Emocional en Transformaci\u00f3n Legal.<\/p><p><span>Coach y mentora de Coaches en Marca Personal, Negocios Digitales y Marketing. Creadora del programa T.O.P.<\/span><\/p><p>Coach de la marca Mauricio Benoist.<\/p><p>Coach Ontol\u00f3gico Profesional con orientaci\u00f3n en Neurociencias aplicadas al Liderazgo y la Educaci\u00f3n, F.O.C.O., Convixion, certificado internacional Academia Europea de Neurociencias, Econom\u00eda y Humanidades. Practitioner Genos International en Inteligencia Emocional,<\/p><p>Abogada con posgrado en Mediaci\u00f3n.<br \/>Con formaci\u00f3n en emprendedurismo, modelos de negocios, marketing, ventas.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"featured_media":0,"menu_order":0,"template":"elementor_header_footer","meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Marca Personal - Escuela de Liderazgo<\/title>\n<meta name=\"description\" content=\"El Coach de equipos \u00e1giles colabora con los equipos para que descubran el camino que les para ser un equipo de alto desempe\u00f1o.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.funi.com.ar\/escuela-de-liderazgo\/curso\/marca-personal\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Marca Personal - Escuela de Liderazgo\" \/>\n<meta property=\"og:description\" content=\"El Coach de equipos \u00e1giles colabora con los equipos para que descubran el camino que les para ser un equipo de alto desempe\u00f1o.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.funi.com.ar\/escuela-de-liderazgo\/curso\/marca-personal\/\" \/>\n<meta property=\"og:site_name\" content=\"Escuela de Liderazgo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Educacion.Funicomapu\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-26T21:48:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.funi.com.ar\/escuela-de-liderazgo\/wp-content\/uploads\/sites\/12\/2023\/03\/575X40-medios-pago.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.funi.com.ar\/escuela-de-liderazgo\/curso\/marca-personal\/\",\"url\":\"https:\/\/www.funi.com.ar\/escuela-de-liderazgo\/curso\/marca-personal\/\",\"name\":\"Marca Personal - Escuela de Liderazgo\",\"isPartOf\":{\"@id\":\"https:\/\/www.funi.com.ar\/escuela-de-liderazgo\/#website\"},\"datePublished\":\"2023-04-02T17:19:09+00:00\",\"dateModified\":\"2026-03-26T21:48:33+00:00\",\"description\":\"El Coach de equipos \u00e1giles colabora con los equipos para que descubran el camino que les para ser un equipo de alto desempe\u00f1o.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.funi.com.ar\/escuela-de-liderazgo\/curso\/marca-personal\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.funi.com.ar\/escuela-de-liderazgo\/curso\/marca-personal\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.funi.com.ar\/escuela-de-liderazgo\/curso\/marca-personal\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/www.funi.com.ar\/escuela-de-liderazgo\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Marca Personal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.funi.com.ar\/escuela-de-liderazgo\/#website\",\"url\":\"https:\/\/www.funi.com.ar\/escuela-de-liderazgo\/\",\"name\":\"Coaching Ontol\u00f3gico Profesional\",\"description\":\"Funi - Despachante de Aduana\",\"publisher\":{\"@id\":\"https:\/\/www.funi.com.ar\/escuela-de-liderazgo\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.funi.com.ar\/escuela-de-liderazgo\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.funi.com.ar\/escuela-de-liderazgo\/#organization\",\"name\":\"FUNI - Coaching Ontol\u00f3gico Profesional\",\"url\":\"https:\/\/www.funi.com.ar\/escuela-de-liderazgo\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/www.funi.com.ar\/escuela-de-liderazgo\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.funi.com.ar\/escuela-de-coaching\/wp-content\/uploads\/sites\/12\/2021\/05\/LOGO_Funi.jpg\",\"contentUrl\":\"https:\/\/www.funi.com.ar\/escuela-de-coaching\/wp-content\/uploads\/sites\/12\/2021\/05\/LOGO_Funi.jpg\",\"width\":757,\"height\":357,\"caption\":\"FUNI - Coaching Ontol\u00f3gico Profesional\"},\"image\":{\"@id\":\"https:\/\/www.funi.com.ar\/escuela-de-liderazgo\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Educacion.Funicomapu\/\",\"https:\/\/www.instagram.com\/funicomapu\/\",\"https:\/\/www.linkedin.com\/company\/funicomapu\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Marca Personal - Escuela de Liderazgo","description":"El Coach de equipos \u00e1giles colabora con los equipos para que descubran el camino que les para ser un equipo de alto desempe\u00f1o.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.funi.com.ar\/escuela-de-liderazgo\/curso\/marca-personal\/","og_locale":"es_ES","og_type":"article","og_title":"Marca Personal - Escuela de Liderazgo","og_description":"El Coach de equipos \u00e1giles colabora con los equipos para que descubran el camino que les para ser un equipo de alto desempe\u00f1o.","og_url":"https:\/\/www.funi.com.ar\/escuela-de-liderazgo\/curso\/marca-personal\/","og_site_name":"Escuela de Liderazgo","article_publisher":"https:\/\/www.facebook.com\/Educacion.Funicomapu\/","article_modified_time":"2026-03-26T21:48:33+00:00","og_image":[{"url":"https:\/\/www.funi.com.ar\/escuela-de-liderazgo\/wp-content\/uploads\/sites\/12\/2023\/03\/575X40-medios-pago.jpg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.funi.com.ar\/escuela-de-liderazgo\/curso\/marca-personal\/","url":"https:\/\/www.funi.com.ar\/escuela-de-liderazgo\/curso\/marca-personal\/","name":"Marca Personal - Escuela de Liderazgo","isPartOf":{"@id":"https:\/\/www.funi.com.ar\/escuela-de-liderazgo\/#website"},"datePublished":"2023-04-02T17:19:09+00:00","dateModified":"2026-03-26T21:48:33+00:00","description":"El Coach de equipos \u00e1giles colabora con los equipos para que descubran el camino que les para ser un equipo de alto desempe\u00f1o.","breadcrumb":{"@id":"https:\/\/www.funi.com.ar\/escuela-de-liderazgo\/curso\/marca-personal\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.funi.com.ar\/escuela-de-liderazgo\/curso\/marca-personal\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.funi.com.ar\/escuela-de-liderazgo\/curso\/marca-personal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.funi.com.ar\/escuela-de-liderazgo\/"},{"@type":"ListItem","position":2,"name":"Marca Personal"}]},{"@type":"WebSite","@id":"https:\/\/www.funi.com.ar\/escuela-de-liderazgo\/#website","url":"https:\/\/www.funi.com.ar\/escuela-de-liderazgo\/","name":"Coaching Ontol\u00f3gico Profesional","description":"Funi - Despachante de Aduana","publisher":{"@id":"https:\/\/www.funi.com.ar\/escuela-de-liderazgo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.funi.com.ar\/escuela-de-liderazgo\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-AR"},{"@type":"Organization","@id":"https:\/\/www.funi.com.ar\/escuela-de-liderazgo\/#organization","name":"FUNI - Coaching Ontol\u00f3gico Profesional","url":"https:\/\/www.funi.com.ar\/escuela-de-liderazgo\/","logo":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/www.funi.com.ar\/escuela-de-liderazgo\/#\/schema\/logo\/image\/","url":"https:\/\/www.funi.com.ar\/escuela-de-coaching\/wp-content\/uploads\/sites\/12\/2021\/05\/LOGO_Funi.jpg","contentUrl":"https:\/\/www.funi.com.ar\/escuela-de-coaching\/wp-content\/uploads\/sites\/12\/2021\/05\/LOGO_Funi.jpg","width":757,"height":357,"caption":"FUNI - Coaching Ontol\u00f3gico Profesional"},"image":{"@id":"https:\/\/www.funi.com.ar\/escuela-de-liderazgo\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Educacion.Funicomapu\/","https:\/\/www.instagram.com\/funicomapu\/","https:\/\/www.linkedin.com\/company\/funicomapu"]}]}},"_links":{"self":[{"href":"https:\/\/www.funi.com.ar\/escuela-de-liderazgo\/wp-json\/wp\/v2\/curso\/39580"}],"collection":[{"href":"https:\/\/www.funi.com.ar\/escuela-de-liderazgo\/wp-json\/wp\/v2\/curso"}],"about":[{"href":"https:\/\/www.funi.com.ar\/escuela-de-liderazgo\/wp-json\/wp\/v2\/types\/curso"}],"version-history":[{"count":98,"href":"https:\/\/www.funi.com.ar\/escuela-de-liderazgo\/wp-json\/wp\/v2\/curso\/39580\/revisions"}],"predecessor-version":[{"id":41130,"href":"https:\/\/www.funi.com.ar\/escuela-de-liderazgo\/wp-json\/wp\/v2\/curso\/39580\/revisions\/41130"}],"wp:attachment":[{"href":"https:\/\/www.funi.com.ar\/escuela-de-liderazgo\/wp-json\/wp\/v2\/media?parent=39580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}